{"id":16628,"date":"2019-04-02T11:42:12","date_gmt":"2019-04-02T09:42:12","guid":{"rendered":"https:\/\/www.myadnlab.com\/blog\/?p=16628"},"modified":"2024-02-05T19:55:19","modified_gmt":"2024-02-05T18:55:19","slug":"tipos-de-pruebas-de-paternidad-diferencias","status":"publish","type":"post","link":"https:\/\/myadnlab.com\/fr\/tipos-de-pruebas-de-paternidad-diferencias\/","title":{"rendered":"\u00bfQu\u00e9 diferencias hay entre una prueba de paternidad informativa y una judicial?"},"content":{"rendered":"<p align=\"justify\">En los \u00faltimos a\u00f1os, la cantidad de pruebas de paternidad que se llevan a cabo en laboratorios ha aumentado considerablemente debido a las dudas que tienen muchos padres y madres sobre la paternidad de sus hijos e hijas. Se trata de una prueba bastante sencilla pero puede variar dependiendo de si la finalidad es meramente informativa o de si se necesita para ser presentada en un informe con validez judicial ante un tribunal o registro.<\/p>\n<h2><strong>Tipos de pruebas de paternidad<\/strong><\/h2>\n<p align=\"justify\">A continuaci\u00f3n te explicamos las particularidades y las principales diferencias entre una <b>prueba de paternidad informativa<\/b> y una <b>prueba de paternidad judicial<\/b>.<\/p>\n<ul>\n<li>\n<h3><a href=\"https:\/\/myadnlab.com\/producto\/prueba-de-paternidad\/\"><strong>Prueba de paternidad informativa<\/strong><\/a><\/h3>\n<\/li>\n<\/ul>\n<p align=\"justify\">Este tipo de pruebas se llevan a cabo cuando el solicitante quiere conocer un <b>resultado para uso particular<\/b>. No tiene ninguna validez judicial y en el informe no aparecen los nombres de los implicados. En estos casos, las pruebas se toman incluso en el domicilio del interesado y se env\u00edan al laboratorio.<\/p>\n<ul>\n<li>\n<h3><a href=\"https:\/\/myadnlab.com\/producto\/prueba-paternidad-valor-judicial\/\"><strong>Prueba de paternidad con valor judicial<\/strong><\/a><\/h3>\n<\/li>\n<\/ul>\n<p align=\"justify\">Las pruebas de paternidad con validez judicial son aquellas que se realizan porque se necesitan en un informe pericial, por lo que en ellas aparecen los nombres de los implicados. Adem\u00e1s, a diferencia de las pruebas informativas, <b>pueden ser usadas en un tribunal de justicia o registro.<\/b><\/p>\n<p align=\"justify\">Eso s\u00ed, para que las pruebas de paternidad sean admitidas ante un tribunal, la toma de las muestras, su identificaci\u00f3n y el env\u00edo hasta el laboratorio deben seguir el proceso adecuado. Por eso, <b>solamente pueden realizarse en un laboratorio<\/b> en el que los participantes sean identificados y las muestras custodiadas con el objetivo de <b>garantizar que los resultados son ver\u00eddicos.<\/b><\/p>\n<p align=\"justify\">En el momento de la toma de las muestras, los participantes deben presentar su documento de identificaci\u00f3n. Adem\u00e1s, en el caso de los adultos, tambi\u00e9n se suele tomar la huella dactilar. Si se trata de un menor que no tiene DNI, se debe llevar una foto y una fotocopia del libro de familia o autorizaci\u00f3n legal que justifique la patria potestad del mismo.<\/p>\n<h2><strong>\u00bfC\u00f3mo se recogen las muestras en las pruebas de paternidad?<\/strong><\/h2>\n<p align=\"justify\">Para poder realizar un test de paternidad de ADN, es necesario recoger <b>muestras biol\u00f3gicas de los implicados<\/b>. La manera m\u00e1s directa y sencilla es hacer un <b>frotis bucal<\/b> con bastoncillos de algod\u00f3n. De esta forma se recogen las c\u00e9lulas del epitelio bucal o la saliva. Pero tambi\u00e9n es habitual recoger manchas de sangre perif\u00e9rica en papel absorbente. Incluso, en otros casos, se pueden usar restos de cad\u00e1veres, como huesos y dientes, o tejido biol\u00f3gico mediante biopsias de parafina.<\/p>\n<p align=\"justify\">Adem\u00e1s, <b>cuando se trata de pruebas de paternidad informativas, tambi\u00e9n pueden usarse otras muestras biol\u00f3gicas recogidas de manera indirecta<\/b>, como el pelo, las u\u00f1as cortadas, las colillas, los caramelos, los chicles, los cepillos de dientes, el semen, objetos con saliva, recipientes de bebidas, el sudor, pa\u00f1uelos con mucosidades, sellos, dientes de leche, cordones umbilicales u orina. Este tipo de muestras no son aceptadas para pruebas de paternidad judiciales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En los \u00faltimos a\u00f1os, la cantidad de pruebas de paternidad que se llevan a cabo en laboratorios ha aumentado considerablemente debido a las dudas que tienen muchos padres y madres sobre la paternidad de sus hijos e hijas. Se trata de una prueba bastante sencilla pero puede variar dependiendo de si la finalidad es meramente [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":16633,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[141],"tags":[],"class_list":["post-16628","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categoria-paternidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfQu\u00e9 diferencia hay entre la prueba de paternidad judicial y la informativa?<\/title>\n<meta name=\"description\" content=\"\u00bfNecesitas una prueba de paternidad pero no conoces las diferencias entre una prueba de paternidad informativa y una con validez judicial?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/myadnlab.com\/fr\/tipos-de-pruebas-de-paternidad-diferencias\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 diferencia hay entre la prueba de paternidad judicial y la informativa?\" \/>\n<meta property=\"og:description\" content=\"\u00bfNecesitas una prueba de paternidad pero no conoces las diferencias entre una prueba de paternidad informativa y una con validez judicial?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/myadnlab.com\/fr\/tipos-de-pruebas-de-paternidad-diferencias\/\" \/>\n<meta property=\"og:site_name\" content=\"MyAdnLab\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/myadnlab\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-02T09:42:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-05T18:55:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/myadnlab.com\/wp-content\/uploads\/2019\/03\/diferencias-entre-prueba-paternidad-informativa-y-judicial.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"myadnlab\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MyAdnLab\" \/>\n<meta name=\"twitter:site\" content=\"@MyAdnLab\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"myadnlab\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/myadnlab.com\\\/fr\\\/tipos-de-pruebas-de-paternidad-diferencias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/myadnlab.com\\\/fr\\\/tipos-de-pruebas-de-paternidad-diferencias\\\/\"},\"author\":{\"name\":\"myadnlab\",\"@id\":\"https:\\\/\\\/myadnlab.com\\\/fr\\\/#\\\/schema\\\/person\\\/3d586b6f9854bb913202583f0273dda9\"},\"headline\":\"\u00bfQu\u00e9 diferencias hay entre una prueba de paternidad informativa y una judicial?\",\"datePublished\":\"2019-04-02T09:42:12+00:00\",\"dateModified\":\"2024-02-05T18:55:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/myadnlab.com\\\/fr\\\/tipos-de-pruebas-de-paternidad-diferencias\\\/\"},\"wordCount\":527,\"publisher\":{\"@id\":\"https:\\\/\\\/myadnlab.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/myadnlab.com\\\/fr\\\/tipos-de-pruebas-de-paternidad-diferencias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/myadnlab.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/diferencias-entre-prueba-paternidad-informativa-y-judicial.jpg\",\"articleSection\":[\"Paternidad\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/myadnlab.com\\\/fr\\\/tipos-de-pruebas-de-paternidad-diferencias\\\/\",\"url\":\"https:\\\/\\\/myadnlab.com\\\/fr\\\/tipos-de-pruebas-de-paternidad-diferencias\\\/\",\"name\":\"\u00bfQu\u00e9 diferencia hay entre la prueba de paternidad judicial y la informativa?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/myadnlab.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/myadnlab.com\\\/fr\\\/tipos-de-pruebas-de-paternidad-diferencias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/myadnlab.com\\\/fr\\\/tipos-de-pruebas-de-paternidad-diferencias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/myadnlab.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/diferencias-entre-prueba-paternidad-informativa-y-judicial.jpg\",\"datePublished\":\"2019-04-02T09:42:12+00:00\",\"dateModified\":\"2024-02-05T18:55:19+00:00\",\"description\":\"\u00bfNecesitas una prueba de paternidad pero no conoces las diferencias entre una prueba de paternidad informativa y una con validez judicial?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/myadnlab.com\\\/fr\\\/tipos-de-pruebas-de-paternidad-diferencias\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/myadnlab.com\\\/fr\\\/tipos-de-pruebas-de-paternidad-diferencias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/myadnlab.com\\\/fr\\\/tipos-de-pruebas-de-paternidad-diferencias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/myadnlab.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/diferencias-entre-prueba-paternidad-informativa-y-judicial.jpg\",\"contentUrl\":\"https:\\\/\\\/myadnlab.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/diferencias-entre-prueba-paternidad-informativa-y-judicial.jpg\",\"width\":1280,\"height\":853,\"caption\":\"Diferencias entre la prueba de paternidad informativa y la judicial\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/myadnlab.com\\\/fr\\\/tipos-de-pruebas-de-paternidad-diferencias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/myadnlab.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 diferencias hay entre una prueba de paternidad informativa y una judicial?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/myadnlab.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/myadnlab.com\\\/fr\\\/\",\"name\":\"MyAdnLab\",\"description\":\"Pruebas de ADN, paternidad, gen\u00e9tica y toxicolog\u00eda\",\"publisher\":{\"@id\":\"https:\\\/\\\/myadnlab.com\\\/fr\\\/#organization\"},\"alternateName\":\"My ADN Lab\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/myadnlab.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/myadnlab.com\\\/fr\\\/#organization\",\"name\":\"MyADNLab\",\"alternateName\":\"My ADN Lab\",\"url\":\"https:\\\/\\\/myadnlab.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/myadnlab.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/myadnlab.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/favicon-2026.png\",\"contentUrl\":\"https:\\\/\\\/myadnlab.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/favicon-2026.png\",\"width\":512,\"height\":512,\"caption\":\"MyADNLab\"},\"image\":{\"@id\":\"https:\\\/\\\/myadnlab.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/myadnlab\",\"https:\\\/\\\/x.com\\\/MyAdnLab\",\"https:\\\/\\\/www.instagram.com\\\/myadnlab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/my-adn-lab\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/myadnlab.com\\\/fr\\\/#\\\/schema\\\/person\\\/3d586b6f9854bb913202583f0273dda9\",\"name\":\"myadnlab\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 diferencia hay entre la prueba de paternidad judicial y la informativa?","description":"\u00bfNecesitas una prueba de paternidad pero no conoces las diferencias entre una prueba de paternidad informativa y una con validez judicial?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/myadnlab.com\/fr\/tipos-de-pruebas-de-paternidad-diferencias\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00bfQu\u00e9 diferencia hay entre la prueba de paternidad judicial y la informativa?","og_description":"\u00bfNecesitas una prueba de paternidad pero no conoces las diferencias entre una prueba de paternidad informativa y una con validez judicial?","og_url":"https:\/\/myadnlab.com\/fr\/tipos-de-pruebas-de-paternidad-diferencias\/","og_site_name":"MyAdnLab","article_publisher":"https:\/\/www.facebook.com\/myadnlab","article_published_time":"2019-04-02T09:42:12+00:00","article_modified_time":"2024-02-05T18:55:19+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/myadnlab.com\/wp-content\/uploads\/2019\/03\/diferencias-entre-prueba-paternidad-informativa-y-judicial.jpg","type":"image\/jpeg"}],"author":"myadnlab","twitter_card":"summary_large_image","twitter_creator":"@MyAdnLab","twitter_site":"@MyAdnLab","twitter_misc":{"\u00c9crit par":"myadnlab","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/myadnlab.com\/fr\/tipos-de-pruebas-de-paternidad-diferencias\/#article","isPartOf":{"@id":"https:\/\/myadnlab.com\/fr\/tipos-de-pruebas-de-paternidad-diferencias\/"},"author":{"name":"myadnlab","@id":"https:\/\/myadnlab.com\/fr\/#\/schema\/person\/3d586b6f9854bb913202583f0273dda9"},"headline":"\u00bfQu\u00e9 diferencias hay entre una prueba de paternidad informativa y una judicial?","datePublished":"2019-04-02T09:42:12+00:00","dateModified":"2024-02-05T18:55:19+00:00","mainEntityOfPage":{"@id":"https:\/\/myadnlab.com\/fr\/tipos-de-pruebas-de-paternidad-diferencias\/"},"wordCount":527,"publisher":{"@id":"https:\/\/myadnlab.com\/fr\/#organization"},"image":{"@id":"https:\/\/myadnlab.com\/fr\/tipos-de-pruebas-de-paternidad-diferencias\/#primaryimage"},"thumbnailUrl":"https:\/\/myadnlab.com\/wp-content\/uploads\/2019\/03\/diferencias-entre-prueba-paternidad-informativa-y-judicial.jpg","articleSection":["Paternidad"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/myadnlab.com\/fr\/tipos-de-pruebas-de-paternidad-diferencias\/","url":"https:\/\/myadnlab.com\/fr\/tipos-de-pruebas-de-paternidad-diferencias\/","name":"\u00bfQu\u00e9 diferencia hay entre la prueba de paternidad judicial y la informativa?","isPartOf":{"@id":"https:\/\/myadnlab.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/myadnlab.com\/fr\/tipos-de-pruebas-de-paternidad-diferencias\/#primaryimage"},"image":{"@id":"https:\/\/myadnlab.com\/fr\/tipos-de-pruebas-de-paternidad-diferencias\/#primaryimage"},"thumbnailUrl":"https:\/\/myadnlab.com\/wp-content\/uploads\/2019\/03\/diferencias-entre-prueba-paternidad-informativa-y-judicial.jpg","datePublished":"2019-04-02T09:42:12+00:00","dateModified":"2024-02-05T18:55:19+00:00","description":"\u00bfNecesitas una prueba de paternidad pero no conoces las diferencias entre una prueba de paternidad informativa y una con validez judicial?","breadcrumb":{"@id":"https:\/\/myadnlab.com\/fr\/tipos-de-pruebas-de-paternidad-diferencias\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/myadnlab.com\/fr\/tipos-de-pruebas-de-paternidad-diferencias\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/myadnlab.com\/fr\/tipos-de-pruebas-de-paternidad-diferencias\/#primaryimage","url":"https:\/\/myadnlab.com\/wp-content\/uploads\/2019\/03\/diferencias-entre-prueba-paternidad-informativa-y-judicial.jpg","contentUrl":"https:\/\/myadnlab.com\/wp-content\/uploads\/2019\/03\/diferencias-entre-prueba-paternidad-informativa-y-judicial.jpg","width":1280,"height":853,"caption":"Diferencias entre la prueba de paternidad informativa y la judicial"},{"@type":"BreadcrumbList","@id":"https:\/\/myadnlab.com\/fr\/tipos-de-pruebas-de-paternidad-diferencias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/myadnlab.com\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 diferencias hay entre una prueba de paternidad informativa y una judicial?"}]},{"@type":"WebSite","@id":"https:\/\/myadnlab.com\/fr\/#website","url":"https:\/\/myadnlab.com\/fr\/","name":"MyAdnLab","description":"Pruebas de ADN, paternidad, gen\u00e9tica y toxicolog\u00eda","publisher":{"@id":"https:\/\/myadnlab.com\/fr\/#organization"},"alternateName":"My ADN Lab","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/myadnlab.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/myadnlab.com\/fr\/#organization","name":"MyADNLab","alternateName":"My ADN Lab","url":"https:\/\/myadnlab.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/myadnlab.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/myadnlab.com\/wp-content\/uploads\/2026\/05\/favicon-2026.png","contentUrl":"https:\/\/myadnlab.com\/wp-content\/uploads\/2026\/05\/favicon-2026.png","width":512,"height":512,"caption":"MyADNLab"},"image":{"@id":"https:\/\/myadnlab.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/myadnlab","https:\/\/x.com\/MyAdnLab","https:\/\/www.instagram.com\/myadnlab\/","https:\/\/www.linkedin.com\/company\/my-adn-lab\/"]},{"@type":"Person","@id":"https:\/\/myadnlab.com\/fr\/#\/schema\/person\/3d586b6f9854bb913202583f0273dda9","name":"myadnlab"}]}},"_links":{"self":[{"href":"https:\/\/myadnlab.com\/fr\/wp-json\/wp\/v2\/posts\/16628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/myadnlab.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/myadnlab.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/myadnlab.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/myadnlab.com\/fr\/wp-json\/wp\/v2\/comments?post=16628"}],"version-history":[{"count":0,"href":"https:\/\/myadnlab.com\/fr\/wp-json\/wp\/v2\/posts\/16628\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/myadnlab.com\/fr\/wp-json\/wp\/v2\/media\/16633"}],"wp:attachment":[{"href":"https:\/\/myadnlab.com\/fr\/wp-json\/wp\/v2\/media?parent=16628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/myadnlab.com\/fr\/wp-json\/wp\/v2\/categories?post=16628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/myadnlab.com\/fr\/wp-json\/wp\/v2\/tags?post=16628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}