{"id":16793,"date":"2020-05-25T09:18:14","date_gmt":"2020-05-25T09:18:14","guid":{"rendered":"https:\/\/www.myadnlab.com\/blog\/?p=16793"},"modified":"2021-03-31T12:22:03","modified_gmt":"2021-03-31T10:22:03","slug":"nutrifit-test-nutrigenetica","status":"publish","type":"post","link":"https:\/\/myadnlab.com\/en\/nutrifit-test-nutrigenetica\/","title":{"rendered":"NutriFit, la prueba de ADN que apuesta por la alimentaci\u00f3n y la vida saludables"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Todos nos preocupamos m\u00e1s de crear <\/span><b>h\u00e1bitos saludables para mejorar nuestro estado de salud y prevenir enfermedades<\/b><span style=\"font-weight: 400;\">. De hecho, cada vez es m\u00e1s habitual acudir a un nutricionista o a un entrenador deportivo para sentirnos mejor con nosotros mismos y ganar salud, adem\u00e1s de calidad de vida. Teniendo en cuenta esta voluntad presente en muchas personas, <\/span><a href=\"\/\"><b>MyAdnLab<\/b><\/a><b> ha ideado la prueba <\/b>nutrigen\u00e9tica<b> NutriFit.<\/b><\/p>\n<p>&nbsp;<\/p>\n<h2><span style=\"font-weight: 400;\">\u00bfQu\u00e9 es NutriFit de MyAdnLab?<\/span><\/h2>\n<p><a href=\"\/producto\/nutrifit\/\"><b>NutriFit es una prueba de ADN<\/b><\/a><span style=\"font-weight: 400;\"> perfecta para aquellos que desean mejorar su estado f\u00edsico y de salud. Con ella, el individuo averiguar\u00e1 cu\u00e1les son sus rasgos gen\u00e9ticos que le condicionan y le favorecen en temas de rendimiento deportivo y en factores nutricionales.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">El procedimiento de este an\u00e1lisis tiene en cuenta las <\/span><b>diferencias gen\u00e9ticas<\/b><span style=\"font-weight: 400;\"> y por tanto, las <\/span><b>diferentes necesidades nutricionales<\/b><span style=\"font-weight: 400;\"> de cada individuo. El resultado se completa con un plan nutricional y unos consejos de estilo de vida saludable totalmente personalizados, basados en las predisposiciones y las necesidades gen\u00e9ticas del sujeto analizado.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Por este motivo, desde MyAdnLab sabemos que no nos equivocamos cuando afirmamos que <\/span><b>NutriFit es una inversi\u00f3n a largo plazo para mejorar la salud y el bienestar de cualquier persona<\/b><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-16797 size-full\" title=\"Nutrifit test nutrigen\u00e9tico. Myadnlab prueba alimentacion saludable\" src=\"https:\/\/myadnlab.com\/wp-content\/uploads\/2020\/05\/jannis-brandt-mmsQUgMLqUo-unsplash-1.jpg\" alt=\"Nutrigen\u00e9tica Nutrifit Myadnlab prueba alimentacion saludable\" width=\"640\" height=\"457\" srcset=\"https:\/\/myadnlab.com\/wp-content\/uploads\/2020\/05\/jannis-brandt-mmsQUgMLqUo-unsplash-1.jpg 640w, https:\/\/myadnlab.com\/wp-content\/uploads\/2020\/05\/jannis-brandt-mmsQUgMLqUo-unsplash-1-300x214.jpg 300w, https:\/\/myadnlab.com\/wp-content\/uploads\/2020\/05\/jannis-brandt-mmsQUgMLqUo-unsplash-1-600x428.jpg 600w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2><span style=\"font-weight: 400;\">\u00bfC\u00f3mo se lleva a cabo NutriFit de MyAdnLab?<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">La <\/span><b>prueba NutriFit<\/b><span style=\"font-weight: 400;\"> es muy sencilla de realizar, ya que no requiere an\u00e1lisis de sangre. En realidad, se realiza con una sencilla muestra de saliva. Al adquirir la prueba NutriFit, el cliente<\/span><b> recibir\u00e1 en casa el kit con las instrucciones y todo lo que necesita para llevar a cabo la prueba<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><span style=\"font-weight: 400;\">\u00bfPara qui\u00e9n est\u00e1 dirigido Nutrifit?<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Las personas que desean someterse al <\/span><b>an\u00e1lisis de NutriFit<\/b><span style=\"font-weight: 400;\"> tienen como objetivo averiguar o llevar a cabo alguna de las siguientes acciones relacionadas con su salud y estado f\u00edsico:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Adaptar su dieta, actividad deportiva y estilo de vida de acuerdo a su c\u00f3digo gen\u00e9tico.<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Alcanzar y mantener su peso ideal.<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Mejorar su estado de salud.<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2><span style=\"font-weight: 400;\">Nutrigen\u00e9tica, la base cient\u00edfica para Nutrifit<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">La mayor\u00eda de dietas, planes nutricionales y\/o deportivos se basan en el estado actual de la persona. Este se determina mediante par\u00e1metros m\u00e9dicos como los resultados de una anal\u00edtica sangu\u00ednea o las medidas f\u00edsicas del individuo: peso, altura, IMC, etc\u00e9tera.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">No obstante, este procedimiento no tiene en cuenta que cada persona tiene una combinaci\u00f3n gen\u00e9tica distinta, y por tanto va a responder de forma distinta a los cambios que se introduzcan.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">La <\/span><b>nutrigen\u00e9tica <\/b><span style=\"font-weight: 400;\">es una disciplina cient\u00edfica que tiene como objetivo estudiar de qu\u00e9 manera las distintas variantes gen\u00e9ticas de las personas influyen en el metabolismo de los nutrientes.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Es decir, <\/span><b>se basa en el hecho que cada persona tiene un c\u00f3digo gen\u00e9tico particular y unas \u00fanicas necesidades nutricionales<\/b><span style=\"font-weight: 400;\">. Por este motivo, el an\u00e1lisis nutrigen\u00e9tico determina c\u00f3mo los cuerpos manejan los nutrientes, siendo muy \u00fatil para crear un plan diet\u00e9tico y de estilo de vida para un individuo.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Por ejemplo, hay personas que tienen m\u00e1s susceptibilidad a aumentar de peso o que metabolizan peor algunas sustancias como la cafe\u00edna. Saber esta informaci\u00f3n permite entender las necesidades espec\u00edficas y actuar en consecuencia.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Si cualquier persona sabe c\u00f3mo es su <\/span><a href=\"https:\/\/es.wikipedia.org\/wiki\/%C3%81cido_desoxirribonucleico\"><span style=\"font-weight: 400;\">ADN<\/span><\/a><span style=\"font-weight: 400;\">, puede hacer cambios que afecten de forma positiva su bienestar y su salud. Los resultados obtenidos de las pruebas nutrigen\u00e9ticas sirven para toda la vida, ya que los genes no cambian.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">No obstante, <\/span><b>desde MyAdnLab afirmamos que las pruebas nutrigen\u00e9ticas no reemplazan el diagn\u00f3stico m\u00e9dico<\/b><span style=\"font-weight: 400;\">. Por ello, siempre es recomendable acudir a una consulta m\u00e9dica para determinar seg\u00fan qu\u00e9 par\u00e1metros.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Eso s\u00ed, <\/span><b>los resultados de NutriFit pueden ser compartidos con profesionales sanitarios para ayudarles a trazar un plan personalizado a unos objetivos de salud<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: center;\"><span style=\"font-weight: 400;\">\u00bfNecesitas m\u00e1s informaci\u00f3n sobre NutriFit? Consulta la p\u00e1gina del producto o ponte en contacto con MyAdnLab.<\/span><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Todos nos preocupamos m\u00e1s de crear h\u00e1bitos saludables para mejorar nuestro estado de salud y prevenir enfermedades. De hecho, cada vez es m\u00e1s habitual acudir a un nutricionista o a un entrenador deportivo para sentirnos mejor con nosotros mismos y ganar salud, adem\u00e1s de calidad de vida. Teniendo en cuenta esta voluntad presente en muchas [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":16818,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[139,143],"tags":[],"class_list":["post-16793","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","category-pruebas-de-adn"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NutriFit, la prueba de ADN que apuesta por la alimentaci\u00f3n y la vida saludables<\/title>\n<meta name=\"description\" content=\"NutriFit es la nueva apuesta de MyAdnLab. \u00bfQuieres saber qu\u00e9 alimentos te van mejor para potenciar y optimizar tu rendimiento deportivo? \u00a1Sigue leyendo!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/myadnlab.com\/en\/nutrifit-test-nutrigenetica\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NutriFit, la prueba de ADN que apuesta por la alimentaci\u00f3n y la vida saludables\" \/>\n<meta property=\"og:description\" content=\"NutriFit es la nueva apuesta de MyAdnLab. \u00bfQuieres saber qu\u00e9 alimentos te van mejor para potenciar y optimizar tu rendimiento deportivo? \u00a1Sigue leyendo!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/myadnlab.com\/en\/nutrifit-test-nutrigenetica\/\" \/>\n<meta property=\"og:site_name\" content=\"MyAdnLab\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/myadnlab\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-25T09:18:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-31T10:22:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/myadnlab.com\/wp-content\/uploads\/2020\/05\/fitness-3168246_640.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"426\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"myadnlab\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MyAdnLab\" \/>\n<meta name=\"twitter:site\" content=\"@MyAdnLab\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"myadnlab\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/myadnlab.com\\\/en\\\/nutrifit-test-nutrigenetica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/myadnlab.com\\\/en\\\/nutrifit-test-nutrigenetica\\\/\"},\"author\":{\"name\":\"myadnlab\",\"@id\":\"https:\\\/\\\/myadnlab.com\\\/en\\\/#\\\/schema\\\/person\\\/3d586b6f9854bb913202583f0273dda9\"},\"headline\":\"NutriFit, la prueba de ADN que apuesta por la alimentaci\u00f3n y la vida saludables\",\"datePublished\":\"2020-05-25T09:18:14+00:00\",\"dateModified\":\"2021-03-31T10:22:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/myadnlab.com\\\/en\\\/nutrifit-test-nutrigenetica\\\/\"},\"wordCount\":690,\"publisher\":{\"@id\":\"https:\\\/\\\/myadnlab.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/myadnlab.com\\\/en\\\/nutrifit-test-nutrigenetica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/myadnlab.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/fitness-3168246_640.jpg\",\"articleSection\":[\"General\",\"Pruebas de ADN\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/myadnlab.com\\\/en\\\/nutrifit-test-nutrigenetica\\\/\",\"url\":\"https:\\\/\\\/myadnlab.com\\\/en\\\/nutrifit-test-nutrigenetica\\\/\",\"name\":\"NutriFit, la prueba de ADN que apuesta por la alimentaci\u00f3n y la vida saludables\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/myadnlab.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/myadnlab.com\\\/en\\\/nutrifit-test-nutrigenetica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/myadnlab.com\\\/en\\\/nutrifit-test-nutrigenetica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/myadnlab.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/fitness-3168246_640.jpg\",\"datePublished\":\"2020-05-25T09:18:14+00:00\",\"dateModified\":\"2021-03-31T10:22:03+00:00\",\"description\":\"NutriFit es la nueva apuesta de MyAdnLab. \u00bfQuieres saber qu\u00e9 alimentos te van mejor para potenciar y optimizar tu rendimiento deportivo? \u00a1Sigue leyendo!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/myadnlab.com\\\/en\\\/nutrifit-test-nutrigenetica\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/myadnlab.com\\\/en\\\/nutrifit-test-nutrigenetica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/myadnlab.com\\\/en\\\/nutrifit-test-nutrigenetica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/myadnlab.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/fitness-3168246_640.jpg\",\"contentUrl\":\"https:\\\/\\\/myadnlab.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/fitness-3168246_640.jpg\",\"width\":640,\"height\":426,\"caption\":\"nutrigenetica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/myadnlab.com\\\/en\\\/nutrifit-test-nutrigenetica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/myadnlab.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NutriFit, la prueba de ADN que apuesta por la alimentaci\u00f3n y la vida saludables\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/myadnlab.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/myadnlab.com\\\/en\\\/\",\"name\":\"MyAdnLab\",\"description\":\"Pruebas de ADN, paternidad, gen\u00e9tica y toxicolog\u00eda\",\"publisher\":{\"@id\":\"https:\\\/\\\/myadnlab.com\\\/en\\\/#organization\"},\"alternateName\":\"My ADN Lab\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/myadnlab.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/myadnlab.com\\\/en\\\/#organization\",\"name\":\"MyADNLab\",\"alternateName\":\"My ADN Lab\",\"url\":\"https:\\\/\\\/myadnlab.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/myadnlab.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/myadnlab.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/favicon-2026.png\",\"contentUrl\":\"https:\\\/\\\/myadnlab.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/favicon-2026.png\",\"width\":512,\"height\":512,\"caption\":\"MyADNLab\"},\"image\":{\"@id\":\"https:\\\/\\\/myadnlab.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/myadnlab\",\"https:\\\/\\\/x.com\\\/MyAdnLab\",\"https:\\\/\\\/www.instagram.com\\\/myadnlab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/my-adn-lab\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/myadnlab.com\\\/en\\\/#\\\/schema\\\/person\\\/3d586b6f9854bb913202583f0273dda9\",\"name\":\"myadnlab\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NutriFit, la prueba de ADN que apuesta por la alimentaci\u00f3n y la vida saludables","description":"NutriFit es la nueva apuesta de MyAdnLab. \u00bfQuieres saber qu\u00e9 alimentos te van mejor para potenciar y optimizar tu rendimiento deportivo? \u00a1Sigue leyendo!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/myadnlab.com\/en\/nutrifit-test-nutrigenetica\/","og_locale":"en_US","og_type":"article","og_title":"NutriFit, la prueba de ADN que apuesta por la alimentaci\u00f3n y la vida saludables","og_description":"NutriFit es la nueva apuesta de MyAdnLab. \u00bfQuieres saber qu\u00e9 alimentos te van mejor para potenciar y optimizar tu rendimiento deportivo? \u00a1Sigue leyendo!","og_url":"https:\/\/myadnlab.com\/en\/nutrifit-test-nutrigenetica\/","og_site_name":"MyAdnLab","article_publisher":"https:\/\/www.facebook.com\/myadnlab","article_published_time":"2020-05-25T09:18:14+00:00","article_modified_time":"2021-03-31T10:22:03+00:00","og_image":[{"width":640,"height":426,"url":"https:\/\/myadnlab.com\/wp-content\/uploads\/2020\/05\/fitness-3168246_640.jpg","type":"image\/jpeg"}],"author":"myadnlab","twitter_card":"summary_large_image","twitter_creator":"@MyAdnLab","twitter_site":"@MyAdnLab","twitter_misc":{"Written by":"myadnlab","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/myadnlab.com\/en\/nutrifit-test-nutrigenetica\/#article","isPartOf":{"@id":"https:\/\/myadnlab.com\/en\/nutrifit-test-nutrigenetica\/"},"author":{"name":"myadnlab","@id":"https:\/\/myadnlab.com\/en\/#\/schema\/person\/3d586b6f9854bb913202583f0273dda9"},"headline":"NutriFit, la prueba de ADN que apuesta por la alimentaci\u00f3n y la vida saludables","datePublished":"2020-05-25T09:18:14+00:00","dateModified":"2021-03-31T10:22:03+00:00","mainEntityOfPage":{"@id":"https:\/\/myadnlab.com\/en\/nutrifit-test-nutrigenetica\/"},"wordCount":690,"publisher":{"@id":"https:\/\/myadnlab.com\/en\/#organization"},"image":{"@id":"https:\/\/myadnlab.com\/en\/nutrifit-test-nutrigenetica\/#primaryimage"},"thumbnailUrl":"https:\/\/myadnlab.com\/wp-content\/uploads\/2020\/05\/fitness-3168246_640.jpg","articleSection":["General","Pruebas de ADN"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/myadnlab.com\/en\/nutrifit-test-nutrigenetica\/","url":"https:\/\/myadnlab.com\/en\/nutrifit-test-nutrigenetica\/","name":"NutriFit, la prueba de ADN que apuesta por la alimentaci\u00f3n y la vida saludables","isPartOf":{"@id":"https:\/\/myadnlab.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/myadnlab.com\/en\/nutrifit-test-nutrigenetica\/#primaryimage"},"image":{"@id":"https:\/\/myadnlab.com\/en\/nutrifit-test-nutrigenetica\/#primaryimage"},"thumbnailUrl":"https:\/\/myadnlab.com\/wp-content\/uploads\/2020\/05\/fitness-3168246_640.jpg","datePublished":"2020-05-25T09:18:14+00:00","dateModified":"2021-03-31T10:22:03+00:00","description":"NutriFit es la nueva apuesta de MyAdnLab. \u00bfQuieres saber qu\u00e9 alimentos te van mejor para potenciar y optimizar tu rendimiento deportivo? \u00a1Sigue leyendo!","breadcrumb":{"@id":"https:\/\/myadnlab.com\/en\/nutrifit-test-nutrigenetica\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/myadnlab.com\/en\/nutrifit-test-nutrigenetica\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/myadnlab.com\/en\/nutrifit-test-nutrigenetica\/#primaryimage","url":"https:\/\/myadnlab.com\/wp-content\/uploads\/2020\/05\/fitness-3168246_640.jpg","contentUrl":"https:\/\/myadnlab.com\/wp-content\/uploads\/2020\/05\/fitness-3168246_640.jpg","width":640,"height":426,"caption":"nutrigenetica"},{"@type":"BreadcrumbList","@id":"https:\/\/myadnlab.com\/en\/nutrifit-test-nutrigenetica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/myadnlab.com\/en\/"},{"@type":"ListItem","position":2,"name":"NutriFit, la prueba de ADN que apuesta por la alimentaci\u00f3n y la vida saludables"}]},{"@type":"WebSite","@id":"https:\/\/myadnlab.com\/en\/#website","url":"https:\/\/myadnlab.com\/en\/","name":"MyAdnLab","description":"Pruebas de ADN, paternidad, gen\u00e9tica y toxicolog\u00eda","publisher":{"@id":"https:\/\/myadnlab.com\/en\/#organization"},"alternateName":"My ADN Lab","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/myadnlab.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/myadnlab.com\/en\/#organization","name":"MyADNLab","alternateName":"My ADN Lab","url":"https:\/\/myadnlab.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/myadnlab.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/myadnlab.com\/wp-content\/uploads\/2026\/05\/favicon-2026.png","contentUrl":"https:\/\/myadnlab.com\/wp-content\/uploads\/2026\/05\/favicon-2026.png","width":512,"height":512,"caption":"MyADNLab"},"image":{"@id":"https:\/\/myadnlab.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/myadnlab","https:\/\/x.com\/MyAdnLab","https:\/\/www.instagram.com\/myadnlab\/","https:\/\/www.linkedin.com\/company\/my-adn-lab\/"]},{"@type":"Person","@id":"https:\/\/myadnlab.com\/en\/#\/schema\/person\/3d586b6f9854bb913202583f0273dda9","name":"myadnlab"}]}},"_links":{"self":[{"href":"https:\/\/myadnlab.com\/en\/wp-json\/wp\/v2\/posts\/16793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/myadnlab.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/myadnlab.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/myadnlab.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/myadnlab.com\/en\/wp-json\/wp\/v2\/comments?post=16793"}],"version-history":[{"count":0,"href":"https:\/\/myadnlab.com\/en\/wp-json\/wp\/v2\/posts\/16793\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/myadnlab.com\/en\/wp-json\/wp\/v2\/media\/16818"}],"wp:attachment":[{"href":"https:\/\/myadnlab.com\/en\/wp-json\/wp\/v2\/media?parent=16793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/myadnlab.com\/en\/wp-json\/wp\/v2\/categories?post=16793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/myadnlab.com\/en\/wp-json\/wp\/v2\/tags?post=16793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}